{"id":82781,"date":"2025-01-29T11:16:03","date_gmt":"2025-01-29T10:16:03","guid":{"rendered":"https:\/\/lladogrup.com\/?p=82781"},"modified":"2025-02-25T16:34:48","modified_gmt":"2025-02-25T15:34:48","slug":"cambios-que-afectan-la-declaracion-de-la-renta-2025","status":"publish","type":"post","link":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/","title":{"rendered":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><b>La campa\u00f1a de la declaraci\u00f3n de la Renta correspondiente al ejercicio fiscal 2024, a realizarse en 2025, llega con importantes modificaciones que afectan a diversos aspectos.\u00a0<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Desde nuevos <\/span><b>m\u00e9todos de pago<\/b><span style=\"font-weight: 400;\"> hasta cambios en los <\/span><b>l\u00edmites de ingresos <\/b><span style=\"font-weight: 400;\">y <\/span><b>obligaciones para colectivos espec\u00edficos<\/b><span style=\"font-weight: 400;\">, estas novedades est\u00e1n dise\u00f1adas para simplificar el tr\u00e1mite para algunos contribuyentes y ampliar las obligaciones para otros, un resumen de novedades que te conviene conocer.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-18876a5718e8d3a77\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-18876a5718e8d3a77 uvc-9743 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-18876a5718e8d3a77 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">Per\u00edodo para presentar la declaraci\u00f3n de la Renta en 2025<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El per\u00edodo para presentar la declaraci\u00f3n de la Renta en 2025, <\/span><b>comenzar\u00e1 el pr\u00f3ximo 2 de abril de 2025<\/b><span style=\"font-weight: 400;\"> y <\/span><b>finalizar\u00e1 el 30 de junio de 2025<\/b><span style=\"font-weight: 400;\">. Este plazo es ligeramente m\u00e1s temprano en comparaci\u00f3n con campa\u00f1as anteriores, permitiendo a los contribuyentes disponer de m\u00e1s tiempo para gestionar su IRPF y el impuesto sobre el patrimonio.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Como en a\u00f1os previos, la presentaci\u00f3n podr\u00e1 realizarse por internet mediante el programa <\/span><b>Renta Web<\/b><span style=\"font-weight: 400;\"> o a trav\u00e9s de la <\/span><b>aplicaci\u00f3n m\u00f3vil de la Agencia Tributaria<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_btn title=\u00bbAsesor\u00eda fiscal\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfas fa-mouse\u00bb css=\u00bb.vc_custom_1738145333785{margin-bottom: 40px !important;}\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Flladogrup.com%2Fes%2Fasesoria%2Fasesoria-fiscal-y-contable-para-empresas%2F|target:_blank\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-6716a5718e8d3b1f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-6716a5718e8d3b1f uvc-5993 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-6716a5718e8d3b1f h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">\u00bfQui\u00e9n est\u00e1 obligado a realizar la declaraci\u00f3n de la Renta 2025?<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Tendr\u00e1n la <\/span><b>obligaci\u00f3n a realizar la declaraci\u00f3n de la Renta,<\/b><span style=\"font-weight: 400;\"> todas aquellas personas f\u00edsicas que en cualquier momento del per\u00edodo impositivo han estado de alta, como <\/span><b>trabajadores por cuenta propia<\/b><span style=\"font-weight: 400;\">, en el <\/span><b>R\u00e9gimen Especial de Trabajadores por Cuenta Propia<\/b><span style=\"font-weight: 400;\"> o <\/span><b>Aut\u00f3nomos<\/b><span style=\"font-weight: 400;\">, o en el <\/span><b>R\u00e9gimen Especial de la Seguridad Social de los Trabajadores del Mar<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><strong>Trabajadores con salarios inferiores a 22.000 euros<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\">Para la campa\u00f1a de 2025, se incrementa el l\u00edmite de ingresos que exime de la obligaci\u00f3n de presentar la declaraci\u00f3n de la Renta. Las personas con un <strong>\u00fanico pagador y rendimientos \u00edntegros del trabajo inferiores a 22.000 euros anuales<\/strong> no tendr\u00e1n que realizar este tr\u00e1mite.<\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\">En el caso de contar <strong>con dos o m\u00e1s pagadores<\/strong>, se eleva el l\u00edmite de los ingresos provenientes del segundo y siguientes pagadores a<strong> 2.500 euros<\/strong>, frente a los 1.500 euros establecidos en el caso anterior. Este cambio pretende aliviar las obligaciones tributarias de los trabajadores con rentas m\u00e1s bajas y reducir la carga administrativa para este grupo.<\/li>\n<\/ul>\n<p><strong>Parados y beneficiarios de prestaciones por desempleo<\/strong><\/p>\n<ul>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\">A partir de 2025, las personas que reciban<strong> prestaciones por desempleo estar\u00e1n obligadas a presentar la declaraci\u00f3n de la Renta<\/strong>, incluso si sus ingresos no alcanzan el m\u00ednimo exento de 15.876 euros anuales. Este cambio busca aumentar la transparencia y el control sobre las prestaciones, asegurando que se declare cualquier ingreso percibido por este concepto.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-69576a5718e8d3b86\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-69576a5718e8d3b86 uvc-4020 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-69576a5718e8d3b86 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">Nuevos m\u00e9todos de pago: Bizum, tarjetas, etc.<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Una de las novedades m\u00e1s destacadas es la <\/span><b>ampliaci\u00f3n de las opciones de pago<\/b><span style=\"font-weight: 400;\">. Por primera vez, los contribuyentes podr\u00e1n pagar el importe de la declaraci\u00f3n mediante<\/span><b> Bizum<\/b><span style=\"font-weight: 400;\">, una alternativa r\u00e1pida y ampliamente utilizada en Espa\u00f1a. Adem\u00e1s, seguir\u00e1n disponibles las <\/span><b>transferencias bancarias<\/b><span style=\"font-weight: 400;\"> y, como novedad adicional, el uso de <\/span><b>tarjetas de cr\u00e9dito o d\u00e9bito.<\/b><span style=\"font-weight: 400;\"> Esta medida busca facilitar el <\/span><b>cumplimiento de las obligaciones fiscales<\/b><span style=\"font-weight: 400;\">, ofreciendo opciones m\u00e1s accesibles y alineadas con los h\u00e1bitos digitales de los ciudadanos.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-9276a5718e8d3be4\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-9276a5718e8d3be4 uvc-8374 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-9276a5718e8d3be4 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">Deducci\u00f3n por obras de mejora de eficiencia energ\u00e9tica en viviendas<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Las cantidades satisfechas por obras realizadas hasta el 31 de diciembre de 2024 para la <\/span><b>reducci\u00f3n de la demanda de calefacci\u00f3n y refrigeraci\u00f3n y la mejora en el consumo de energ\u00eda <\/b><span style=\"font-weight: 400;\">primaria no renovable seguir\u00e1n siendo deducibles en la Renta de 2024. Tanto en la vivienda habitual como en cualquier otra que se tuviera arrendada para su uso como vivienda en ese momento o en expectativa de alquiler. Siempre que, en este \u00faltimo caso, la vivienda se alquile antes del 31 de diciembre de 2025.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_single_image image=\u00bb82788&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column][vc_column width=\u00bb1\/3&#8243;]<div id=\"ultimate-heading-79066a5718e8d3c3f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-79066a5718e8d3c3f uvc-2074  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-79066a5718e8d3c3f h3'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h3 style=\"font-weight:bold;color:#fe5d3a;\">Subscriu-te a la nostra newsletter<\/h3><\/div><\/div><p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Formulario de contacto no encontrado.<\/p>[\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-54906a5718e8d3e9c\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-54906a5718e8d3e9c uvc-4146 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-54906a5718e8d3e9c h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">Deducciones para promover la adquisici\u00f3n para particulares de veh\u00edculos el\u00e9ctricos<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Con efectos desde el 30 de junio de 2023 se a\u00f1adieron por el <\/span><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2023-15135#a1-101\"><span style=\"font-weight: 400;\">art\u00edculo 189 del Real Decreto-ley 5\/2023, de 28 de junio<\/span><\/a><span style=\"font-weight: 400;\"> dos <\/span><b>nuevas deducciones sobre los veh\u00edculos el\u00e9ctricos<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><b>Deducci\u00f3n por la adquisici\u00f3n de veh\u00edculos el\u00e9ctricos \u2018enchufables\u2019 y de pila de combustible<\/b><span style=\"font-weight: 400;\">. Los contribuyentes pueden deducir el 15 % del valor de adquisici\u00f3n de la compra de un veh\u00edculo el\u00e9ctrico nuevo. La base m\u00e1xima de la deducci\u00f3n ser\u00e1 20.000 euros, constituida por el valor de adquisici\u00f3n del veh\u00edculo, gastos y tributos inherentes a la adquisici\u00f3n. Por ello, se deber\u00e1n descontar aquellas cuant\u00edas que hubieran sido subvencionadas o fueran a serlo a trav\u00e9s de un programa de ayudas p\u00fablicas.<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><b>Deducci\u00f3n por la instalaci\u00f3n de infraestructuras de recarga<\/b><span style=\"font-weight: 400;\">. Los contribuyentes podr\u00e1n deducir el 15 % de las cantidades satisfechas desde el 30 de junio de 2023 hasta el 31 de diciembre de 2024. Para la instalaci\u00f3n durante dicho per\u00edodo en un inmueble de su propiedad de sistemas de recarga de bater\u00edas para veh\u00edculos el\u00e9ctricos no afectas a una actividad econ\u00f3mica. La base m\u00e1xima anual de esta deducci\u00f3n ser\u00e1 de 4.000 euros anuales.<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-18276a5718e8d3f29\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-18276a5718e8d3f29 uvc-6031 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-18276a5718e8d3f29 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">Reducci\u00f3n por arrendamiento de vivienda para los contratos de arrendamiento celebrados desde el 1 de enero de 2024<\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mediante la <\/span><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2023-12203\"><span style=\"font-weight: 400;\">Ley 12\/2023, de 24 de mayo<\/span><\/a><span style=\"font-weight: 400;\">, por el <\/span><b>derecho a la vivienda<\/b><span style=\"font-weight: 400;\"> se modula la actual reducci\u00f3n del 60 % estableci\u00e9ndose que el rendimiento neto positivo se reducir\u00e1:<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En un 90 % cuando se haya formalizado por el mismo arrendador un nuevo contrato de arrendamiento sobre una vivienda situada en zonas de mercado residencial tensionado. Con una reducci\u00f3n en la renta de al menos un 5 % sobre el contrato anterior.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En un 70 % cuando: no se cumplan los requisitos anteriores, se trate de la incorporaci\u00f3n al mercado de viviendas destinadas al alquiler en zonas de mercado residencial tensionado y se alquilen a j\u00f3venes de entre 18 y 35 a\u00f1os en dichas \u00e1reas.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En un 60 % cuando, no cumpli\u00e9ndose los requisitos de los dos apartados anteriores, la vivienda hubiera sido objeto de una actuaci\u00f3n de rehabilitaci\u00f3n que hubiera finalizado en los dos a\u00f1os anteriores a la fecha de celebraci\u00f3n del contrato.<\/span><\/li>\n<li style=\"font-weight: 400; text-align: justify;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En un 50 % en cualquier otro caso.<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00bbstretch_row\u00bb bg_type=\u00bbimage\u00bb bg_override=\u00bbfull\u00bb css=\u00bb.vc_custom_1704903641721{margin-bottom: 30px !important;background-color: #fff2ed !important;}\u00bb][vc_column][vc_row_inner css=\u00bb.vc_custom_1704899436080{margin-bottom: 30px !important;}\u00bb][vc_column_inner css=\u00bb.vc_custom_1704899344593{padding-right: 25px !important;padding-left: 30px !important;}\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<h3 class=\"form-control second-textarea\" style=\"text-align: center;\"><strong>\u00bfTienes dudas sobre la declaraci\u00f3n de la Renta 2025?<\/strong><\/h3>\n<p>[\/vc_column_text][vc_column_text][\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"4\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/82781#wpcf7-f4-o1\" method=\"post\" class=\"wpcf7-form init 98099fcddabd cmatic-conn cmatic-aud-0 cmatic-mapd0-0 cmatic-v097806 cmatic-sent-0 cmatic-total-529\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label>Nombre*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Escribe tu nombre y apellidos\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label>Email*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label>Tel\u00e9fono*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"llado-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"llado-tel\" \/><\/span><\/label>\n<\/p>\n<p><label>Mensaje<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"llado-mensaje\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Motivo de la consulta\" name=\"llado-mensaje\"><\/textarea><\/span><\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-272\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-272\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> He le\u00eddo y acepto la <a href=\"https:\/\/lladogrup.com\/es\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-423\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-423\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Acepto recibir informaci\u00f3n sobre las actividades, servicios y productos de Llad\u00f3 Grup Consultor.\n<\/p>\n<p><span style=\"margin-top: 10px;\"><\/span>\n<\/p>\n\n<p><span style=\"margin-bottom: 10px;\"><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"52\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-45826a5718e8d4fbf\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-45826a5718e8d4fbf uvc-4109 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-45826a5718e8d4fbf h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#fe5d3a;margin-bottom:20px;\">C\u00f3mo puede ayudarte el equipo fiscal de Llad\u00f3 Grup Consultor <\/h2><\/div><\/div>[vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La <\/span><b>campa\u00f1a de la Renta 2025<\/b><span style=\"font-weight: 400;\"> presenta novedades significativas que pueden impactar en tu declaraci\u00f3n. Para optimizar tus resultados y evitar sorpresas desagradables y cumplir con tus <\/span><b>obligaciones tributarias<\/b><span style=\"font-weight: 400;\">, te ofrecemos un equipo especializado en las declaraciones de la Renta para asesorarte y realizar tu <\/span><b>declaraci\u00f3n de la Renta 2025<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text css=\u00bb\u00bb] La campa\u00f1a de la declaraci\u00f3n de la Renta correspondiente al ejercicio fiscal 2024, a realizarse en 2025, llega con importantes modificaciones que afectan a diversos aspectos.\u00a0 Desde nuevos m\u00e9todos de pago hasta cambios en los l\u00edmites de ingresos y obligaciones para colectivos espec\u00edficos, estas novedades est\u00e1n dise\u00f1adas para simplificar el&hellip;<\/p>\n","protected":false},"author":2,"featured_media":82786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[614,613,621,622,615,623,616,2195,617,2255],"tags":[],"class_list":["post-82781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autonomos","category-clientes","category-estrategia-es","category-fiscal-es","category-gran-empresa-es","category-juridico","category-particulares","category-patrimonial-es","category-pymes","category-renda-es","category-614","category-613","category-621","category-622","category-615","category-623","category-616","category-2195","category-617","category-2255","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-<\/title>\n<meta name=\"description\" content=\"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Llad\u00f3 Grup\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T10:16:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T15:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LladogrupSB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LladogrupSB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/\"},\"author\":{\"name\":\"LladogrupSB\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"headline\":\"Cambios que afectan a la declaraci\u00f3n de la Renta 2025\",\"datePublished\":\"2025-01-29T10:16:03+00:00\",\"dateModified\":\"2025-02-25T15:34:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/\"},\"wordCount\":1669,\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20250122-Novetats_Renda_2025-520x272-1.jpg\",\"articleSection\":[\"Aut\u00f3nomos\",\"Clientes\",\"Estrategia\",\"Fiscal\",\"Gran empresa\",\"Jur\u00eddico\",\"Particulares\",\"Patrimonial\",\"Pymes\",\"Renda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/\",\"name\":\"Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20250122-Novetats_Renda_2025-520x272-1.jpg\",\"datePublished\":\"2025-01-29T10:16:03+00:00\",\"dateModified\":\"2025-02-25T15:34:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"description\":\"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20250122-Novetats_Renda_2025-520x272-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20250122-Novetats_Renda_2025-520x272-1.jpg\",\"width\":520,\"height\":272,\"caption\":\"Cropped shot of pretty young woman uses online banking app on laptop computer, calcualtes something on calculator, works with documents or financial taxes, man stands near, kitchen interior. SSUCv3H4sIAAAAAAAEAJ2RQW7DIBBF95V6B4u1LdkQY6dXiboYA3FHIaYCnCqKfPcANhLrruC\\\/4cP84fX5UVVkAoeCfFWvqIJGrVfnLXg0S8BtfXAl0RuLoCOMbEsV4jz41SkXrziQAK\\\/mcHaHhz+\\\/c9l1lQupGByhREhdMLdOiWW01f927pvvHAVmtYhnargIYpVWsAe57EfJ7c8rey+jPVAqU2hYJZoi5cMI0NHAipt\\\/LQpc5sJm\\\/I+y5cTCyM29AIvxqZMjGJFhpFF2rOO0H\\\/iZM8roaeQjyd9gxA1l2SvK6Bhafm6vMDRhFc1J9tBMlI5Ne+UdCMkU64cwqe0NU7xyIw4CAAA=\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/cambios-que-afectan-la-declaracion-de-la-renta-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambios que afectan a la declaraci\u00f3n de la Renta 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/\",\"name\":\"Llad\u00f3 Grup\",\"description\":\"Consultoria i gestoria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lladogrup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\",\"name\":\"LladogrupSB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"caption\":\"LladogrupSB\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-","description":"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-","og_description":"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!","og_url":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/","og_site_name":"Llad\u00f3 Grup","article_published_time":"2025-01-29T10:16:03+00:00","article_modified_time":"2025-02-25T15:34:48+00:00","og_image":[{"width":520,"height":272,"url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg","type":"image\/jpeg"}],"author":"LladogrupSB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LladogrupSB","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#article","isPartOf":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/"},"author":{"name":"LladogrupSB","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"headline":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025","datePublished":"2025-01-29T10:16:03+00:00","dateModified":"2025-02-25T15:34:48+00:00","mainEntityOfPage":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/"},"wordCount":1669,"image":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg","articleSection":["Aut\u00f3nomos","Clientes","Estrategia","Fiscal","Gran empresa","Jur\u00eddico","Particulares","Patrimonial","Pymes","Renda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/","url":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/","name":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025 -Llad\u00f3-","isPartOf":{"@id":"https:\/\/lladogrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#primaryimage"},"image":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg","datePublished":"2025-01-29T10:16:03+00:00","dateModified":"2025-02-25T15:34:48+00:00","author":{"@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"description":"Este a\u00f1o la campa\u00f1a de la Renta, lleva cambios que pueden afectar en tu declaraci\u00f3n de la Renta 2025 y obligaciones fiscales. \u00a1Cons\u00faltanos!","breadcrumb":{"@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#primaryimage","url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg","contentUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2025\/01\/20250122-Novetats_Renda_2025-520x272-1.jpg","width":520,"height":272,"caption":"Cropped shot of pretty young woman uses online banking app on laptop computer, calcualtes something on calculator, works with documents or financial taxes, man stands near, kitchen interior. SSUCv3H4sIAAAAAAAEAJ2RQW7DIBBF95V6B4u1LdkQY6dXiboYA3FHIaYCnCqKfPcANhLrruC\/4cP84fX5UVVkAoeCfFWvqIJGrVfnLXg0S8BtfXAl0RuLoCOMbEsV4jz41SkXrziQAK\/mcHaHhz+\/c9l1lQupGByhREhdMLdOiWW01f927pvvHAVmtYhnargIYpVWsAe57EfJ7c8rey+jPVAqU2hYJZoi5cMI0NHAipt\/LQpc5sJm\/I+y5cTCyM29AIvxqZMjGJFhpFF2rOO0H\/iZM8roaeQjyd9gxA1l2SvK6Bhafm6vMDRhFc1J9tBMlI5Ne+UdCMkU64cwqe0NU7xyIw4CAAA="},{"@type":"BreadcrumbList","@id":"https:\/\/lladogrup.com\/es\/cambios-que-afectan-la-declaracion-de-la-renta-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lladogrup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cambios que afectan a la declaraci\u00f3n de la Renta 2025"}]},{"@type":"WebSite","@id":"https:\/\/lladogrup.com\/#website","url":"https:\/\/lladogrup.com\/","name":"Llad\u00f3 Grup","description":"Consultoria i gestoria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lladogrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a","name":"LladogrupSB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","caption":"LladogrupSB"}}]}},"_links":{"self":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/82781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/comments?post=82781"}],"version-history":[{"count":6,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/82781\/revisions"}],"predecessor-version":[{"id":82810,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/82781\/revisions\/82810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media\/82786"}],"wp:attachment":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media?parent=82781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/categories?post=82781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/tags?post=82781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}