{"id":67701,"date":"2023-03-15T12:02:01","date_gmt":"2023-03-15T11:02:01","guid":{"rendered":"https:\/\/lladogrup.com\/?p=67701"},"modified":"2023-03-15T16:10:46","modified_gmt":"2023-03-15T15:10:46","slug":"que-es-un-expediente-de-regulacion-de-empleo","status":"publish","type":"post","link":"https:\/\/lladogrup.com\/es\/que-es-un-expediente-de-regulacion-de-empleo\/","title":{"rendered":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=\u00bb67706&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-54546a97c358b5187\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-54546a97c358b5187 uvc-9402  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-54546a97c358b5187 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?<\/h1><\/div><\/div>[\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>En los \u00faltimos a\u00f1os tanto por la crisis sanitaria de 2020 como la crisis financiera del 2008, nos familiarizamos con los conceptos ERE y ERTE, como unas medidas de ajuste colectivas que disponen las empresas para proceder a la suspensi\u00f3n o reducci\u00f3n de la jornada laboral, as\u00ed como tambi\u00e9n para la extinci\u00f3n del contrato de trabajo de trabajadores. <\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675250171834{padding-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-34806a97c358b521f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-34806a97c358b521f uvc-8399 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-34806a97c358b521f h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo?<\/h2><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Un <strong>Expediente de Regulaci\u00f3n de Empleo<\/strong> es un procedimiento legal que se tramita ante la Administraci\u00f3n y que permite a las <strong>empresas<\/strong> <strong>en dificultades<\/strong> aplicar medidas colectivas de flexibilizaci\u00f3n y\/o de ajuste de las relaciones laborales de la empresa.<\/p>\n<p>Para iniciar dicho procedimiento ha de encontrarse la empresa en los siguientes supuestos:[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675250171834{padding-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-37906a97c358b527f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-37906a97c358b527f uvc-5925 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-37906a97c358b527f h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">Causas para tramitar un Expediente de Regulaci\u00f3n de Empleo<\/h2><\/div><\/div>[vc_column_text]Las principales causas para poder una empresa <strong>tramitar un ERE<\/strong> pueden ser las siguientes:<\/p>\n<ul>\n<li><strong>Causas econ\u00f3micas<\/strong>. Cuando la empresa se encuentra en una situaci\u00f3n econ\u00f3mica negativa, como la existencia de p\u00e9rdidas actuales o previstas o la disminuci\u00f3n persistente y continuada de su nivel de ingresos ordinarios o de ventas.<\/li>\n<li><strong>Causas organizativas.<\/strong> En aquellos casos en que objetivamente se produce la necesidad de cambios en la estructura organizativa de la empresa, en el dise\u00f1o y funcionamiento de los sistemas y m\u00e9todos de trabajo o de la producci\u00f3n, para una gesti\u00f3n y funcionamiento m\u00e1s eficiente, y que generen sobrantes de plantilla.<\/li>\n<li><strong>Causas t\u00e9cnicas<\/strong>. En aquellas ocasiones en las que es preciso introducir innovaciones en los medios o instrumentos de producci\u00f3n, como una nueva tecnolog\u00eda y ello suponga tambi\u00e9n la necesidad de una reducci\u00f3n de mano de obra.<\/li>\n<li><strong>Causas productivas.<\/strong> Si se producen cambios en la demanda de servicios y\/o productos que la empresa pretende colocar en el mercado.<\/li>\n<li><strong>Fuerza mayor<\/strong>. Cuando se produce un hecho externo ajeno a la esfera de la actividad de la empresa, como incendio, inundaci\u00f3n, explosi\u00f3n, etc.<\/li>\n<li><strong>Extinci\u00f3n de la personalidad jur\u00eddica del empresario<\/strong>. En funci\u00f3n del n\u00famero de trabajadores despedidos y obedeciendo a criterios legales y causas objetivas, procediendo a la liquidaci\u00f3n de la sociedad.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_btn title=\u00bbNecesitas asesoramiento sobre ERE o ERTE?\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfas fa-mouse\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Flladogrup.com%2Fes%2Fcontacto%2F|target:_blank\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675250171834{padding-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-73496a97c358b52e4\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-73496a97c358b52e4 uvc-1714 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-73496a97c358b52e4 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">Tipos de Expediente de Regulaci\u00f3n de Empleo<\/h2><\/div><\/div>[vc_column_text]Los <strong>Expedientes de Regulaci\u00f3n de Empleo<\/strong> pueden ser:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>De extinci\u00f3n colectiva de contratos (ERE)<\/strong>. Supone el <strong>cese<\/strong> <strong>definitivo<\/strong> de la relaci\u00f3n laboral de algunos o incluso de todos sus trabajadores. Es conocido como despido colectivo y ser\u00e1 el procedimiento obligado seg\u00fan el volumen de despidos a ejecutar.<\/li>\n<li style=\"text-align: justify;\"><strong>De suspensi\u00f3n y\/o reducci\u00f3n temporal de contratos (ERTE)<\/strong>. La empresa <strong>suspende y\/o reduce de forma flexible y de manera t<\/strong><strong>emporal<\/strong> los contratos de todos o parte de los trabajadores. No precisa de ning\u00fan volumen m\u00ednimo de trabajadores afectados para su tramitaci\u00f3n.<\/li>\n<li style=\"text-align: justify;\"><strong>Mecanismo RED, de flexibilidad y estabilizaci\u00f3n del empleo. <\/strong>Es un <strong>expediente de suspensi\u00f3n y\/o reducci\u00f3n temporal y flexible de contratos <\/strong>(ERTE) ante situaciones de crisis a nivel SECTORIAL. Previa activaci\u00f3n por el Consejo de Ministros, necesitar\u00e1 la aprobaci\u00f3n de la Autoridad Laboral en cada empresa que lo solicite.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675249503108{background-color: #dddddd !important;}\u00bb][vc_column][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<h3 class=\"form-control second-textarea\" style=\"text-align: center;\">Expl\u00edcanos tu caso<\/h3>\n<p style=\"text-align: center;\">Somos un equipo de profesionales con experiencia en la <strong>tramitaci\u00f3n de ERE y ERTE<\/strong>, inf\u00f3rmate sin compromiso.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u00a0Nos puedes contactar v\u00eda <strong>WhatsApp <a href=\"https:\/\/bit.ly\/38ZKw99\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a><\/strong> o facilitarnos tus datos y contactaremos contigo.<\/p>\n<p>[\/vc_column_text][vc_btn title=\u00bbContacta con nosotros\u00bb color=\u00bbdanger\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Flladogrup.com%2Fes%2Fcontacte%2F|target:_blank\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675250171834{padding-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-75746a97c358b5339\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-75746a97c358b5339 uvc-743 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-75746a97c358b5339 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">\u00bfQu\u00e9 derechos ampara la ley al trabajador ante un ERTE o un ERE?<\/h2><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Ante un <strong>despido<\/strong> <strong>por un<\/strong> <strong>ERTE<\/strong> las personas trabajadoras afectadas podr\u00e1n:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Percibir la prestaci\u00f3n por desempleo a que tengan derecho durante el tiempo de suspensi\u00f3n o reducci\u00f3n.<\/li>\n<li>Conservaran asimismo la antig\u00fcedad y dem\u00e1s derechos contractuales. La empresa cotizar\u00e1 a la seguridad social durante ese periodo.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Ante un <strong>despido en un ERE<\/strong> la persona trabajadora tiene derecho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Indemnizaci\u00f3n por despido que se indique en el expediente,<\/li>\n<li>y a las prestaciones por desempleo que le correspondan.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En lo relativo a la <strong>indemnizaci\u00f3n por despido<\/strong>, hay que aclarar que la m\u00ednima establecida es de <strong>20 d\u00edas por a\u00f1o trabajado con un m\u00e1ximo de 12 mensualidades<\/strong>. En casos inferiores al a\u00f1o, la cantidad se prorratear\u00e1.\u00a0 Si la empresa no puede hacer frente a las indemnizaciones de los trabajadores despedidos, el Fondo de Garant\u00eda Social debe garantizar el cobro, todo y que con unos l\u00edmites.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1675250171834{padding-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-83246a97c358b538b\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-83246a97c358b538b uvc-2792 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-83246a97c358b538b h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">\u00bfC\u00f3mo podemos ayudarte en un Expediente de Regulaci\u00f3n de Empleo (ERE)?<\/h2><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\">En la tramitaci\u00f3n de los <strong>ERTES <\/strong>o <strong>ERES<\/strong> es imprescindible atenenerse escrupulosamente al procedimiento y plazos legales, para su aceptaci\u00f3n por la Administraci\u00f3n y tambi\u00e9n para su defensa ante una impugnaci\u00f3n por parte de los trabajadores. Asimimo la obligaci\u00f3n legal de negociaci\u00f3n de dicho expediente, as\u00ed como la intervenci\u00f3n de la Inspecci\u00f3n de Trabajo y de la Autoridad Laboral, requiere el concurso de profesionales especializados y con experiencia.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1669219009705{margin-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<strong>Llad\u00f3 Grup Consultor<\/strong>, dispone de profesionales especializados con una experiencia de m\u00e1s de 20 a\u00f1os en este tipo de <strong>expedientes laborales<\/strong>, y que pone a tu disposici\u00f3n cuando lo necesites.[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bb\u00bfQuieres saber m\u00e1s de nuestros servicios laborales?\u00bb color=\u00bbdanger\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfas fa-mouse\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Flladogrup.com%2Fes%2Fasesoria%2Flaboral-para-empresas%2F|target:_blank\u00bb css=\u00bb.vc_custom_1678878015306{margin-top: 30px !important;}\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=\u00bb67706&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text] En los \u00faltimos a\u00f1os tanto por la crisis sanitaria de 2020 como la crisis financiera del 2008, nos familiarizamos con los conceptos ERE y ERTE, como unas medidas de ajuste colectivas que disponen las empresas para proceder a la suspensi\u00f3n o reducci\u00f3n de la jornada&hellip;<\/p>\n","protected":false},"author":2,"featured_media":67712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[614,613,615,626,616,617],"tags":[],"class_list":["post-67701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autonomos","category-clientes","category-gran-empresa-es","category-laboral-es","category-particulares","category-pymes","category-614","category-613","category-615","category-626","category-616","category-617","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-<\/title>\n<meta name=\"description\" content=\"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Llad\u00f3 Grup\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-15T11:02:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-15T15:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LladogrupSB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LladogrupSB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/que-es-un-expediente-de-regulacion-de-empleo\\\/\"},\"author\":{\"name\":\"LladogrupSB\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"headline\":\"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?\",\"datePublished\":\"2023-03-15T11:02:01+00:00\",\"dateModified\":\"2023-03-15T15:10:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/que-es-un-expediente-de-regulacion-de-empleo\\\/\"},\"wordCount\":1321,\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230315-Que_es_un_ERE-520x272esp-1.jpg\",\"articleSection\":[\"Aut\u00f3nomos\",\"Clientes\",\"Gran empresa\",\"Laboral\",\"Particulares\",\"Pymes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/que-es-un-expediente-de-regulacion-de-empleo\\\/\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/\",\"name\":\"Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230315-Que_es_un_ERE-520x272esp-1.jpg\",\"datePublished\":\"2023-03-15T11:02:01+00:00\",\"dateModified\":\"2023-03-15T15:10:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"description\":\"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230315-Que_es_un_ERE-520x272esp-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230315-Que_es_un_ERE-520x272esp-1.jpg\",\"width\":520,\"height\":272,\"caption\":\"Expedientes laborales ERE y ERTE Llado Grup\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/microsites\\\/registro-salarial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/\",\"name\":\"Llad\u00f3 Grup\",\"description\":\"Consultoria i gestoria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lladogrup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\",\"name\":\"LladogrupSB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"caption\":\"LladogrupSB\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-","description":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-","og_description":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.","og_url":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/","og_site_name":"Llad\u00f3 Grup","article_published_time":"2023-03-15T11:02:01+00:00","article_modified_time":"2023-03-15T15:10:46+00:00","og_image":[{"width":520,"height":272,"url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg","type":"image\/jpeg"}],"author":"LladogrupSB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LladogrupSB","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#article","isPartOf":{"@id":"https:\/\/lladogrup.com\/es\/que-es-un-expediente-de-regulacion-de-empleo\/"},"author":{"name":"LladogrupSB","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"headline":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?","datePublished":"2023-03-15T11:02:01+00:00","dateModified":"2023-03-15T15:10:46+00:00","mainEntityOfPage":{"@id":"https:\/\/lladogrup.com\/es\/que-es-un-expediente-de-regulacion-de-empleo\/"},"wordCount":1321,"image":{"@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg","articleSection":["Aut\u00f3nomos","Clientes","Gran empresa","Laboral","Particulares","Pymes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lladogrup.com\/es\/que-es-un-expediente-de-regulacion-de-empleo\/","url":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/","name":"Qu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo? -Llad\u00f3 Grup-","isPartOf":{"@id":"https:\/\/lladogrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#primaryimage"},"image":{"@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg","datePublished":"2023-03-15T11:02:01+00:00","dateModified":"2023-03-15T15:10:46+00:00","author":{"@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"description":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n? Causas para tramitar un Expediente de Regulaci\u00f3n de Ocupaci\u00f3n y sus tipos.","breadcrumb":{"@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#primaryimage","url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg","contentUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/03\/20230315-Que_es_un_ERE-520x272esp-1.jpg","width":520,"height":272,"caption":"Expedientes laborales ERE y ERTE Llado Grup"},{"@type":"BreadcrumbList","@id":"https:\/\/lladogrup.com\/es\/microsites\/registro-salarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lladogrup.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es un Expediente de Regulaci\u00f3n de Empleo (ERE)?"}]},{"@type":"WebSite","@id":"https:\/\/lladogrup.com\/#website","url":"https:\/\/lladogrup.com\/","name":"Llad\u00f3 Grup","description":"Consultoria i gestoria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lladogrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a","name":"LladogrupSB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","caption":"LladogrupSB"}}]}},"_links":{"self":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/67701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/comments?post=67701"}],"version-history":[{"count":9,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/67701\/revisions"}],"predecessor-version":[{"id":67750,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/67701\/revisions\/67750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media\/67712"}],"wp:attachment":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media?parent=67701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/categories?post=67701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/tags?post=67701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}