{"id":66638,"date":"2023-01-25T10:24:13","date_gmt":"2023-01-25T09:24:13","guid":{"rendered":"https:\/\/lladogrup.com\/?p=66638"},"modified":"2023-01-25T11:05:19","modified_gmt":"2023-01-25T10:05:19","slug":"novedades-en-seguridad-social-y-pensiones-2023","status":"publish","type":"post","link":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/","title":{"rendered":"Novedades en Seguridad Social y Pensiones 2023"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=\u00bb66643&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-30156a04b129264e6\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-30156a04b129264e6 uvc-2415  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-30156a04b129264e6 h1'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h1 style=\"--font-weight:theme;\">Novedades en Seguridad Social y Pensiones 2023<\/h1><\/div><\/div>[\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social, tanto por las cotizaciones, como las prestaciones.<\/strong><\/p>\n<p style=\"text-align: justify;\">El gobierno lleva tiempo trabajando en cambios con el fin de poder mantener la viabilidad del sistema de pensiones, que ya se aplicaron en el 2022. Y que la fuerte subida del 8,5% en las prestaciones se une el inicio de la incorporaci\u00f3n a la jubilaci\u00f3n de la generaci\u00f3n del \u2018baby boom\u2019, la m\u00e1s numerosa de la historia.<\/p>\n<p style=\"text-align: justify;\">As\u00ed que este 2023 tambi\u00e9n se incorporaran novedades para poder hacer frente con nuevas cuant\u00edas y requisitos a la temprano de poder gestionar las jubilaciones.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n, os explicamos el resumen de las novedades en Seguridad Social y Pensiones por 2023:<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-886a04b1292658f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-886a04b1292658f uvc-7501 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-886a04b1292658f h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">Cotizaciones a la Seguridad Social para 2023<\/h2><\/div><\/div>[vc_column_text]<strong>R\u00e9gimen de trabajadores aut\u00f3nomos<\/strong><\/p>\n<p style=\"text-align: justify;\">El 1 de enero de 2023 entr\u00f3 en vigor el <strong>nuevo modelo de cotizaci\u00f3n para los trabajadores que cotizan bajo el r\u00e9gimen de aut\u00f3nomos<\/strong> (RETA). Este nuevo modelo consiste en 15 tramos de cotizaci\u00f3n, cada tramo cuenta con una base m\u00ednima y una base m\u00e1xima de cotizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Los <strong>tramos de cotizaci\u00f3n<\/strong> se establecen en funci\u00f3n de los ingresos reales o rendimientos netos que se calcular\u00e1n deduciendo de los ingresos todos los gastos producidos en ejercicio de la actividad y necesarios para la obtenci\u00f3n de estos ingresos. Sobre esta cantidad, se aplicar\u00e1 adicionalmente una deducci\u00f3n por gastos gen\u00e9ricos del 7% que ser\u00e1 del 3% en el caso los aut\u00f3nomos societarios. El resultado ser\u00e1n los denominados rendimientos netos y sobre ellos se aplicar\u00e1 el tipo de cotizaci\u00f3n correspondiente.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb66649&#8243; img_size=\u00bbfull\u00bb css=\u00bb.vc_custom_1674641057603{padding-top: 70px !important;}\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb66651&#8243; img_size=\u00bbfull\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1669219009705{margin-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text]<strong>R\u00e9gimen general<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Una de las medidas que afectar\u00e1 las <strong>cotizaciones de los trabajadores bajo el r\u00e9gimen general <\/strong>es el incremento de la base m\u00e1xima de cotizaci\u00f3n en un 8,6% situ\u00e1ndose en un importe de 4.495,39 euros mensuales (53.944,66 euros anuales).<\/li>\n<li style=\"text-align: justify;\">Otra de las medidas del 2023 es el <strong>Mecanismo de Equidad Intergeneracional (MEI)<\/strong>, que se estableci\u00f3 en sustituci\u00f3n en el factor de sostenibilidad y el que busca es aumentar los ingresos y favorecer la sostenibilidad del sistema p\u00fablico de pensiones. Esta medida aumenta el porcentaje de cotizaciones en un 0,6%, del cual 0,5% ser\u00e1 a cargo de la empresa y 0,1% a cargo del empleado.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_btn title=\u00bb\u00bfNecesitas asesoramiento laboral para tu empresa?\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfas fa-mouse\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Flladogrup.com%2Fes%2Fcontacto%2F|target:_blank\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column css=\u00bb.vc_custom_1674641083094{padding-top: 10px !important;}\u00bb]<div id=\"ultimate-heading-32876a04b129265f4\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-32876a04b129265f4 uvc-7711 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-32876a04b129265f4 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">Prestaciones a la Seguridad Social para 2023<\/h2><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Las <strong>pensiones contributivas de la Seguridad Social<\/strong> se ver\u00e1n incrementadas en un 8,5% situ\u00e1ndose la pensi\u00f3n m\u00e1xima en 3.058,81 euros mensuales en 14 pagas (42.823,34 euros mensuales).<\/p>\n<p style=\"text-align: justify;\">Esta subida se ha determinado con la media resultante de los doce meses comprendidos entre diciembre de 2021 y noviembre de 2022, conforme al que se establece en la reforma de la Ley 21\/2021, de 28 de diciembre, de garant\u00eda del poder adquisitivo de las pensiones y otras medidas de refuerzo de la sostenibilidad financiera y social del sistema p\u00fablico de pensiones.<\/p>\n<p style=\"text-align: justify;\">Se incrementar\u00e1n tambi\u00e9n en este porcentaje las pensiones de las clases pasivas (funcionarios p\u00fablicos) y el ingreso m\u00ednimo vital. El incremento de las pensiones no contributivas ser\u00e1 del 15%.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1669218923481{background-color: #796e65 !important;}\u00bb][vc_column][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<h3 class=\"form-control second-textarea\" style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u00bfCrees que es interesante lo que est\u00e1s leyendo? \u00a1Subscr\u00edbete al blog!!<\/span><\/h3>\n<p>[\/vc_column_text]<p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Formulario de contacto no encontrado.<\/p>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109361052{padding-bottom: 20px !important;}\u00bb][vc_column]<div id=\"ultimate-heading-18976a04b12926900\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-18976a04b12926900 uvc-682 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-18976a04b12926900 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;margin-bottom:20px;\">Cambios en materia de Previsi\u00f3n Social para 2023<\/h2><\/div><\/div>[vc_column_text]<strong>Nuevos l\u00edmites de aportaci\u00f3n en los Planes de Pensiones 2023<\/strong><\/p>\n<p style=\"text-align: justify;\">Los <strong>l\u00edmites de aportaciones a planes de pensiones<\/strong> han sufrido modificaciones en los \u00faltimos dos a\u00f1os, en el 2023 no es una excepci\u00f3n y empieza con una nueva modificaci\u00f3n de los l\u00edmites quedando establecidos a partir de 1 de enero de la siguiente forma:<\/p>\n<ol>\n<li style=\"text-align: justify;\">a) El l\u00edmite general conjunto para aportaciones de la empresa y del empleado continuar\u00e1 siendo de 1.500 euros anuales.<\/li>\n<li style=\"text-align: justify;\">b) Este l\u00edmite se incrementar\u00e1 en 8.500 euros anuales si el incremento proviene de contribuciones empresariales, o de aportaciones del trabajador al mismo instrumento de previsi\u00f3n social por importe igual o inferior al resultado de aplicar a la contribuci\u00f3n empresarial un coeficiente, que depende del importe anual de la contribuci\u00f3n empresarial:<\/li>\n<\/ol>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_single_image image=\u00bb66653&#8243; img_size=\u00bbfull\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">En caso de que el trabajador obtenga en el ejercicio rendimientos \u00edntegros del trabajo superiores a 60.000 euros, su aportaci\u00f3n no podr\u00e1 superar a la de la empresa.<\/p>\n<p style=\"text-align: justify;\">El l\u00edmite de aportaci\u00f3n a planes de pensiones de 1.500 de los trabajadores bajo el r\u00e9gimen de aut\u00f3nomos se incrementar\u00e1 en 4.250 siempre que las aportaciones se realicen a <strong>planes de pensiones<\/strong> simplificados de trabajadores por cuenta propia o aut\u00f3nomos.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><strong>Reducci\u00f3n de las cuotas de la Seguridad Social 2023<\/strong><\/p>\n<p style=\"text-align: justify;\">Durante este 2023 se aplicar\u00e1 la <strong>reducci\u00f3n de las cuotas empresariales por contingencias comunes <\/strong>por el incremento en la cuota que derive directamente de la aportaci\u00f3n empresarial a planes de pensiones.<\/p>\n<p style=\"text-align: justify;\">El importe m\u00e1ximo mensual que podr\u00e1 ser reducido ser\u00e1 de 119,31 \u20ac, que resulta de multiplicar por 13 la cuota resultante de aplicar en la base m\u00ednima diaria de cotizaci\u00f3n del grupo 8 del R\u00e9gimen General de la Seguridad Social para contingencias comunes (38,89), el tipo general de cotizaci\u00f3n a cargo de la empresa para la cobertura de estas contingencias (23,60%).<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1669219009705{margin-top: 20px !important;padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text]En <strong>Llad\u00f3 Grup Consultor<\/strong> te ofrecemos un <strong>asesoramiento laboral integral<\/strong> y personalizado en funci\u00f3n de tus necesidades.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=\u00bb66643&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1631109896967{padding-bottom: 20px !important;}\u00bb][vc_column][vc_column_text] Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social, tanto por las cotizaciones, como las prestaciones. El gobierno lleva tiempo trabajando en cambios con el fin de poder mantener la viabilidad del sistema de pensiones, que ya&hellip;<\/p>\n","protected":false},"author":2,"featured_media":66647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[614,613,615,626,616,617],"tags":[],"class_list":["post-66638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autonomos","category-clientes","category-gran-empresa-es","category-laboral-es","category-particulares","category-pymes","category-614","category-613","category-615","category-626","category-616","category-617","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-<\/title>\n<meta name=\"description\" content=\"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Llad\u00f3 Grup\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T09:24:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-25T10:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LladogrupSB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"LladogrupSB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/\"},\"author\":{\"name\":\"LladogrupSB\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"headline\":\"Novedades en Seguridad Social y Pensiones 2023\",\"datePublished\":\"2023-01-25T09:24:13+00:00\",\"dateModified\":\"2023-01-25T10:05:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/\"},\"wordCount\":1251,\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg\",\"articleSection\":[\"Aut\u00f3nomos\",\"Clientes\",\"Gran empresa\",\"Laboral\",\"Particulares\",\"Pymes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/\",\"name\":\"Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg\",\"datePublished\":\"2023-01-25T09:24:13+00:00\",\"dateModified\":\"2023-01-25T10:05:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\"},\"description\":\"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg\",\"contentUrl\":\"https:\\\/\\\/lladogrup.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg\",\"width\":520,\"height\":272,\"caption\":\"Novedades Seguridad Social y Pensiones 2023 Llado Grup\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/novedades-en-seguridad-social-y-pensiones-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lladogrup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades en Seguridad Social y Pensiones 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#website\",\"url\":\"https:\\\/\\\/lladogrup.com\\\/\",\"name\":\"Llad\u00f3 Grup\",\"description\":\"Consultoria i gestoria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lladogrup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lladogrup.com\\\/#\\\/schema\\\/person\\\/fae891704510562cc35f2a910871bb7a\",\"name\":\"LladogrupSB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g\",\"caption\":\"LladogrupSB\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-","description":"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-","og_description":"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...","og_url":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/","og_site_name":"Llad\u00f3 Grup","article_published_time":"2023-01-25T09:24:13+00:00","article_modified_time":"2023-01-25T10:05:19+00:00","og_image":[{"width":520,"height":272,"url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg","type":"image\/jpeg"}],"author":"LladogrupSB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"LladogrupSB","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#article","isPartOf":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/"},"author":{"name":"LladogrupSB","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"headline":"Novedades en Seguridad Social y Pensiones 2023","datePublished":"2023-01-25T09:24:13+00:00","dateModified":"2023-01-25T10:05:19+00:00","mainEntityOfPage":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/"},"wordCount":1251,"image":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg","articleSection":["Aut\u00f3nomos","Clientes","Gran empresa","Laboral","Particulares","Pymes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/","url":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/","name":"Novedades en Seguridad Social y Pensiones 2023 -Llad\u00f3 Grup-","isPartOf":{"@id":"https:\/\/lladogrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#primaryimage"},"image":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg","datePublished":"2023-01-25T09:24:13+00:00","dateModified":"2023-01-25T10:05:19+00:00","author":{"@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a"},"description":"Este a\u00f1o 2023 ha empezado con numerosas novedades en materia de previsi\u00f3n social y de Seguridad Social...","breadcrumb":{"@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#primaryimage","url":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg","contentUrl":"https:\/\/lladogrup.com\/wp-content\/uploads\/2023\/01\/20230119-Novetats_SegSocial_Pensions2023-520x272esp.jpg","width":520,"height":272,"caption":"Novedades Seguridad Social y Pensiones 2023 Llado Grup"},{"@type":"BreadcrumbList","@id":"https:\/\/lladogrup.com\/es\/novedades-en-seguridad-social-y-pensiones-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lladogrup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades en Seguridad Social y Pensiones 2023"}]},{"@type":"WebSite","@id":"https:\/\/lladogrup.com\/#website","url":"https:\/\/lladogrup.com\/","name":"Llad\u00f3 Grup","description":"Consultoria i gestoria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lladogrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lladogrup.com\/#\/schema\/person\/fae891704510562cc35f2a910871bb7a","name":"LladogrupSB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8dab0ac617b31013790aba77d3585a0fc0040d861b8f20b54660334fea26d66?s=96&d=mm&r=g","caption":"LladogrupSB"}}]}},"_links":{"self":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/66638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/comments?post=66638"}],"version-history":[{"count":9,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/66638\/revisions"}],"predecessor-version":[{"id":66713,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/posts\/66638\/revisions\/66713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media\/66647"}],"wp:attachment":[{"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/media?parent=66638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/categories?post=66638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lladogrup.com\/es\/wp-json\/wp\/v2\/tags?post=66638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}